{"id":9019,"date":"2022-10-11T10:09:10","date_gmt":"2022-10-11T08:09:10","guid":{"rendered":"https:\/\/locsshop.eu\/shop\/sorte-locs-solbriller-roed-bandana\/"},"modified":"2025-10-21T11:46:07","modified_gmt":"2025-10-21T09:46:07","slug":"sorte-locs-solbriller-roed-bandana","status":"publish","type":"product","link":"https:\/\/locsshop.eu\/es\/shop\/black-locs-sunglasses-red-bandana\/","title":{"rendered":"Gafas de sol negras Locs \u2013 Red Bandana"},"content":{"rendered":"<h2><strong>Gafas de sol negras Locs con logos plateados en las varillas y estampado de bandana roja<\/strong><\/h2>\n<h4><\/h4>\n<h4>Locs Sunglasses es una popular marca estadounidense de gafas de sol conocida por su actitud incondicional. Como una de las marcas de anteojos de sol m\u00e1s buscadas en los EE. UU. e internacionalmente, Locs ha mantenido sus dise\u00f1os caracter\u00edsticos y su estilo feroz a lo largo de los a\u00f1os.<br \/>\nLas gafas de sol Locs tienen logotipos geniales, bonitos detalles y un estilo que es un poco m\u00e1s duro que otros. Perfecto para aquellos de ustedes que tienen un poco de actitud.<\/h4>\n<p>&nbsp;<\/p>\n<h4><strong><em>Detalles:<br \/>\n<\/em><\/strong><br \/>\nAncho interior: 13 cm<br \/>\nAltura: 3,6 cm<br \/>\nLongitud de la varilla: 12,5 cm<\/h4>\n<h4>Material: Pl\u00e1stico<br \/>\nProtecci\u00f3n UV400<br \/>\nCE aprobado<\/h4>\n<h4><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-10637 size-thumbnail\" src=\"https:\/\/bazarsalg.dk\/wp-content\/uploads\/Locs-Logo-280x280.jpg\" alt=\"\" width=\"280\" height=\"280\" \/><\/h4>\n<h4><em>Historia LOCS<\/em><\/h4>\n<p><em>En las d\u00e9cadas de 1970 y 1980, las gafas de sol Locs eran muy populares entre los j\u00f3venes y defin\u00edan el estilo LA. Influenciados por la cultura latinoamericana de Los \u00c1ngeles y derivados de la palabra espa\u00f1ola &quot;loco&quot;, originalmente los usaban los cholos y luego se hicieron populares entre todos los g\u00e1nsteres del \u00e1rea de Los \u00c1ngeles. Los pandilleros se refer\u00edan a algunos de sus miembros m\u00e1s salvajes y activos o incluso mentalmente perturbados como &quot;locos&quot;. M\u00e1s tarde, el t\u00e9rmino y el comportamiento asociado se hicieron muy populares entre los Crips en particular y, en menor medida, entre los Bloods. Era tan com\u00fan en el lenguaje Crip que se acort\u00f3 a Loc y se us\u00f3 como sufijo en los nombres de algunos pandilleros.<\/em><\/p>\n<p><em>en la d\u00e9cada de 1990, muchos de los raperos m\u00e1s importantes tambi\u00e9n usaban gafas de sol Locs, por ejemplo, Eazy E, Snoop Dogg y muchos otros raperos conocidos. As\u00ed que las gafas de sol se hicieron muy conocidas y se usaron en muchas pel\u00edculas de g\u00e1nsteres estadounidenses.<\/em><\/p>\n<p><em>Hoy en d\u00eda, las gafas de sol Locs no solo son populares en California, sino tambi\u00e9n en todo Estados Unidos y el resto del mundo. La marca ahora tiene un atractivo m\u00e1s amplio en todos los grupos de consumidores. Una de las razones de esta popularidad es la glorificaci\u00f3n del perfil de LA Gangster a trav\u00e9s de la m\u00fasica, las pel\u00edculas y, por supuesto, los medios. Como los raperos g\u00e1nsteres aparec\u00edan constantemente en los medios de comunicaci\u00f3n por la prensa negativa, se los ve\u00eda usando estas gafas hardcore y el estilo se extendi\u00f3 r\u00e1pidamente por las calles de Los \u00c1ngeles. Con la creciente popularidad, r\u00e1pidamente los ayud\u00f3 a pasar a la corriente principal y ahora son populares entre los artistas y actores famosos.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p><strong>LOCS \u2013 8LOC9003-BDNA<\/strong><br \/>\nMontura negra \u2013 Gafas oscuras<br \/>\nPatr\u00f3n de pa\u00f1uelo rojo en el exterior de los postes.<br \/>\nMarco de pl\u00e1stico<br \/>\nUV400<br \/>\nCE aprobado<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-10637\" src=\"https:\/\/bazarsalg.dk\/wp-content\/uploads\/Locs-Logo.jpg\" alt=\"\" width=\"200\" height=\"200\" \/><\/p>","protected":false},"featured_media":9020,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1101,1049],"product_tag":[1113,1100],"class_list":["post-9019","product","type-product","status-publish","has-post-thumbnail","product_cat-locs-solbriller","product_cat-premium-solbriller","product_tag-8loc9003-bdna","product_tag-locs","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sorte Locs Solbriller - R\u00f8d Bandana | K\u00f8b online her | LOCS<\/title>\n<meta name=\"description\" content=\"K\u00f8b Sorte Locs Solbriller - R\u00f8d Bandana her | EU&#039;s st\u00f8rste udvalg af LOCS solbriller | Vi sender fra EU - Ingen ekstra import udgifter\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/locsshop.eu\/es\/shop\/black-locs-sunglasses-red-bandana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sorte Locs Solbriller - R\u00f8d Bandana | K\u00f8b online her | LOCS\" \/>\n<meta property=\"og:description\" content=\"K\u00f8b Sorte Locs Solbriller - R\u00f8d Bandana her | EU&#039;s st\u00f8rste udvalg af LOCS solbriller | Vi sender fra EU - Ingen ekstra import udgifter\" \/>\n<meta property=\"og:url\" content=\"https:\/\/locsshop.eu\/es\/shop\/black-locs-sunglasses-red-bandana\/\" \/>\n<meta property=\"og:site_name\" content=\"Locs Sunglasses - LOCS Supplier in EU\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-21T09:46:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/locsshop.eu\/wp-content\/uploads\/2022\/10\/8LOC9003BDNA4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/locsshop.eu\\\/shop\\\/sorte-locs-solbriller-roed-bandana\\\/\",\"url\":\"https:\\\/\\\/locsshop.eu\\\/shop\\\/sorte-locs-solbriller-roed-bandana\\\/\",\"name\":\"Sorte Locs Solbriller - R\u00f8d Bandana | K\u00f8b online her | LOCS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/locsshop.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/locsshop.eu\\\/shop\\\/sorte-locs-solbriller-roed-bandana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/locsshop.eu\\\/shop\\\/sorte-locs-solbriller-roed-bandana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/locsshop.eu\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/8LOC9003BDNA4.jpg\",\"datePublished\":\"2022-10-11T08:09:10+00:00\",\"dateModified\":\"2025-10-21T09:46:07+00:00\",\"description\":\"K\u00f8b Sorte Locs Solbriller - R\u00f8d Bandana her | EU's st\u00f8rste udvalg af LOCS solbriller | Vi sender fra EU - Ingen ekstra import udgifter\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/locsshop.eu\\\/shop\\\/sorte-locs-solbriller-roed-bandana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/locsshop.eu\\\/shop\\\/sorte-locs-solbriller-roed-bandana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/locsshop.eu\\\/shop\\\/sorte-locs-solbriller-roed-bandana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/locsshop.eu\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/8LOC9003BDNA4.jpg\",\"contentUrl\":\"https:\\\/\\\/locsshop.eu\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/8LOC9003BDNA4.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/locsshop.eu\\\/shop\\\/sorte-locs-solbriller-roed-bandana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/locsshop.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/locsshop.eu\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sorte Locs Solbriller &#8211; R\u00f8d Bandana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/locsshop.eu\\\/#website\",\"url\":\"https:\\\/\\\/locsshop.eu\\\/\",\"name\":\"Locs Sunglasses - LOCS Supplier in EU\",\"description\":\"We sell cheap LOCS Sunglasses\",\"publisher\":{\"@id\":\"https:\\\/\\\/locsshop.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/locsshop.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/locsshop.eu\\\/#organization\",\"name\":\"Locsshop.eu\",\"url\":\"https:\\\/\\\/locsshop.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/locsshop.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/locsshop.eu\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Locsshop-logo.png\",\"contentUrl\":\"https:\\\/\\\/locsshop.eu\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Locsshop-logo.png\",\"width\":930,\"height\":200,\"caption\":\"Locsshop.eu\"},\"image\":{\"@id\":\"https:\\\/\\\/locsshop.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gafas de sol Locs negras - Pa\u00f1uelo rojo | Compra online aqu\u00ed | LOC","description":"Comprar gafas de sol Black Locs - Red Bandana aqu\u00ed | La mayor selecci\u00f3n de gafas de sol LOCS de la UE | Enviamos desde la UE - Sin costos adicionales de importaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/locsshop.eu\/es\/shop\/black-locs-sunglasses-red-bandana\/","og_locale":"es_ES","og_type":"article","og_title":"Sorte Locs Solbriller - R\u00f8d Bandana | K\u00f8b online her | LOCS","og_description":"K\u00f8b Sorte Locs Solbriller - R\u00f8d Bandana her | EU's st\u00f8rste udvalg af LOCS solbriller | Vi sender fra EU - Ingen ekstra import udgifter","og_url":"https:\/\/locsshop.eu\/es\/shop\/black-locs-sunglasses-red-bandana\/","og_site_name":"Locs Sunglasses - LOCS Supplier in EU","article_modified_time":"2025-10-21T09:46:07+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/locsshop.eu\/wp-content\/uploads\/2022\/10\/8LOC9003BDNA4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/locsshop.eu\/shop\/sorte-locs-solbriller-roed-bandana\/","url":"https:\/\/locsshop.eu\/shop\/sorte-locs-solbriller-roed-bandana\/","name":"Gafas de sol Locs negras - Pa\u00f1uelo rojo | Compra online aqu\u00ed | LOC","isPartOf":{"@id":"https:\/\/locsshop.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/locsshop.eu\/shop\/sorte-locs-solbriller-roed-bandana\/#primaryimage"},"image":{"@id":"https:\/\/locsshop.eu\/shop\/sorte-locs-solbriller-roed-bandana\/#primaryimage"},"thumbnailUrl":"https:\/\/locsshop.eu\/wp-content\/uploads\/2022\/10\/8LOC9003BDNA4.jpg","datePublished":"2022-10-11T08:09:10+00:00","dateModified":"2025-10-21T09:46:07+00:00","description":"Comprar gafas de sol Black Locs - Red Bandana aqu\u00ed | La mayor selecci\u00f3n de gafas de sol LOCS de la UE | Enviamos desde la UE - Sin costos adicionales de importaci\u00f3n","breadcrumb":{"@id":"https:\/\/locsshop.eu\/shop\/sorte-locs-solbriller-roed-bandana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/locsshop.eu\/shop\/sorte-locs-solbriller-roed-bandana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/locsshop.eu\/shop\/sorte-locs-solbriller-roed-bandana\/#primaryimage","url":"https:\/\/locsshop.eu\/wp-content\/uploads\/2022\/10\/8LOC9003BDNA4.jpg","contentUrl":"https:\/\/locsshop.eu\/wp-content\/uploads\/2022\/10\/8LOC9003BDNA4.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/locsshop.eu\/shop\/sorte-locs-solbriller-roed-bandana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/locsshop.eu\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/locsshop.eu\/shop\/"},{"@type":"ListItem","position":3,"name":"Sorte Locs Solbriller &#8211; R\u00f8d Bandana"}]},{"@type":"WebSite","@id":"https:\/\/locsshop.eu\/#website","url":"https:\/\/locsshop.eu\/","name":"Gafas de sol Locs - Proveedor LOCS en la UE","description":"Vendemos Gafas de Sol LOCS baratas","publisher":{"@id":"https:\/\/locsshop.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/locsshop.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/locsshop.eu\/#organization","name":"Locsshop.eu","url":"https:\/\/locsshop.eu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/locsshop.eu\/#\/schema\/logo\/image\/","url":"https:\/\/locsshop.eu\/wp-content\/uploads\/2022\/02\/Locsshop-logo.png","contentUrl":"https:\/\/locsshop.eu\/wp-content\/uploads\/2022\/02\/Locsshop-logo.png","width":930,"height":200,"caption":"Locsshop.eu"},"image":{"@id":"https:\/\/locsshop.eu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/locsshop.eu\/es\/wp-json\/wp\/v2\/product\/9019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/locsshop.eu\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/locsshop.eu\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/locsshop.eu\/es\/wp-json\/wp\/v2\/comments?post=9019"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/locsshop.eu\/es\/wp-json\/wp\/v2\/media\/9020"}],"wp:attachment":[{"href":"https:\/\/locsshop.eu\/es\/wp-json\/wp\/v2\/media?parent=9019"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/locsshop.eu\/es\/wp-json\/wp\/v2\/product_brand?post=9019"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/locsshop.eu\/es\/wp-json\/wp\/v2\/product_cat?post=9019"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/locsshop.eu\/es\/wp-json\/wp\/v2\/product_tag?post=9019"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}