{"id":10242,"date":"2023-05-09T13:09:52","date_gmt":"2023-05-09T11:09:52","guid":{"rendered":"https:\/\/locsshop.eu\/shop\/klassiske-damesolbriller-let-brun-turtle-brune-glas\/"},"modified":"2024-08-12T14:41:08","modified_gmt":"2024-08-12T12:41:08","slug":"klassiske-damesolbriller-let-brun-turtle-brune-glas","status":"publish","type":"product","link":"https:\/\/locsshop.eu\/fr\/shop\/klassiske-damesolbriller-let-brun-turtle-brune-glas\/","title":{"rendered":"Lunettes de soleil classiques pour femmes - Tortue marron clair | Lunettes marron"},"content":{"rendered":"<h2>Belles lunettes de soleil classiques pour femmes<\/h2>\n<p>Belles lunettes de soleil pour femmes dans un style classique.<br \/>\nCeux-ci sont dans un cadre marron avec une d\u00e9coration de tortue l\u00e9g\u00e8re sur le devant et des barres.<br \/>\nIls ont aussi d&#039;agr\u00e9ables verres plats marron<\/p>\n<p>Absolument parfait pour un usage quotidien, les sorties shopping, les visites de caf\u00e9s, la plage et les vacances.<\/p>\n<p>Largeur int\u00e9rieure : 13,7 cm.<br \/>\nHauteur. 4,7 cm.<br \/>\nLongueur c\u00f4t\u00e9 int\u00e9rieur : 13,8 cm.<\/p>\n<p>Mati\u00e8re : Plastique et m\u00e9tal<br \/>\nProtection UV<br \/>\nHomologu\u00e9 CE<\/p>","protected":false},"excerpt":{"rendered":"<p><strong>Lunettes de soleil classiques pour femmes<br \/>\n<\/strong>Tortue marron clair<br \/>\nVerres plats marron<\/p>\n<p>Parfait pour tous les jours et les vacances<\/p>\n<p>Protection UV400.<br \/>\nApprouv\u00e9 CE.<\/p>","protected":false},"featured_media":10243,"comment_status":"open","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_brand":[],"product_cat":[1026,1027,1025],"product_tag":[1339,1340,870],"class_list":["post-10242","product","type-product","status-publish","has-post-thumbnail","product_cat-dame-solbriller","product_cat-andre-dame-solbriller","product_cat-billige-solbriller","product_tag-23-054","product_tag-damesolbriller","product_tag-p693","first","outofstock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Klassiske damesolbriller - Let brun turtle | Brune glas | K\u00f8b online her | LOCS<\/title>\n<meta name=\"description\" content=\"K\u00f8b Klassiske damesolbriller - Let brun turtle | Brune glas her | EU&#039;s st\u00f8rste udvalg af LOCS solbriller | Vi sender fra EU - Ingen ekstra import udgifter\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/locsshop.eu\/fr\/shop\/klassiske-damesolbriller-let-brun-turtle-brune-glas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Klassiske damesolbriller - Let brun turtle | Brune glas | K\u00f8b online her | LOCS\" \/>\n<meta property=\"og:description\" content=\"K\u00f8b Klassiske damesolbriller - Let brun turtle | Brune glas her | EU&#039;s st\u00f8rste udvalg af LOCS solbriller | Vi sender fra EU - Ingen ekstra import udgifter\" \/>\n<meta property=\"og:url\" content=\"https:\/\/locsshop.eu\/fr\/shop\/klassiske-damesolbriller-let-brun-turtle-brune-glas\/\" \/>\n<meta property=\"og:site_name\" content=\"Locs Sunglasses - LOCS Supplier in EU\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-12T12:41:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/locsshop.eu\/wp-content\/uploads\/2023\/05\/23-054-BNTE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/locsshop.eu\\\/shop\\\/klassiske-damesolbriller-let-brun-turtle-brune-glas\\\/\",\"url\":\"https:\\\/\\\/locsshop.eu\\\/shop\\\/klassiske-damesolbriller-let-brun-turtle-brune-glas\\\/\",\"name\":\"Klassiske damesolbriller - Let brun turtle | Brune glas | K\u00f8b online her | LOCS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/locsshop.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/locsshop.eu\\\/shop\\\/klassiske-damesolbriller-let-brun-turtle-brune-glas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/locsshop.eu\\\/shop\\\/klassiske-damesolbriller-let-brun-turtle-brune-glas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/locsshop.eu\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/23-054-BNTE.jpg\",\"datePublished\":\"2023-05-09T11:09:52+00:00\",\"dateModified\":\"2024-08-12T12:41:08+00:00\",\"description\":\"K\u00f8b Klassiske damesolbriller - Let brun turtle | Brune glas her | EU's st\u00f8rste udvalg af LOCS solbriller | Vi sender fra EU - Ingen ekstra import udgifter\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/locsshop.eu\\\/shop\\\/klassiske-damesolbriller-let-brun-turtle-brune-glas\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/locsshop.eu\\\/shop\\\/klassiske-damesolbriller-let-brun-turtle-brune-glas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/locsshop.eu\\\/shop\\\/klassiske-damesolbriller-let-brun-turtle-brune-glas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/locsshop.eu\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/23-054-BNTE.jpg\",\"contentUrl\":\"https:\\\/\\\/locsshop.eu\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/23-054-BNTE.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/locsshop.eu\\\/shop\\\/klassiske-damesolbriller-let-brun-turtle-brune-glas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/locsshop.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/locsshop.eu\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Klassiske damesolbriller &#8211; Let brun turtle | Brune glas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/locsshop.eu\\\/#website\",\"url\":\"https:\\\/\\\/locsshop.eu\\\/\",\"name\":\"Locs Sunglasses - LOCS Supplier in EU\",\"description\":\"We sell cheap LOCS Sunglasses\",\"publisher\":{\"@id\":\"https:\\\/\\\/locsshop.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/locsshop.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/locsshop.eu\\\/#organization\",\"name\":\"Locsshop.eu\",\"url\":\"https:\\\/\\\/locsshop.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/locsshop.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/locsshop.eu\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Locsshop-logo.png\",\"contentUrl\":\"https:\\\/\\\/locsshop.eu\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Locsshop-logo.png\",\"width\":930,\"height\":200,\"caption\":\"Locsshop.eu\"},\"image\":{\"@id\":\"https:\\\/\\\/locsshop.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lunettes de soleil classiques pour femmes - Tortue marron clair | Lunettes marron | Achetez en ligne ici | LOCS","description":"Acheter Lunettes de soleil classiques pour femmes - Tortue marron clair | Lunettes marron ici | La plus grande s\u00e9lection de lunettes de soleil LOCS de l&#039;UE | Nous exp\u00e9dions depuis l&#039;UE - Pas de frais d&#039;importation suppl\u00e9mentaires","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/locsshop.eu\/fr\/shop\/klassiske-damesolbriller-let-brun-turtle-brune-glas\/","og_locale":"fr_FR","og_type":"article","og_title":"Klassiske damesolbriller - Let brun turtle | Brune glas | K\u00f8b online her | LOCS","og_description":"K\u00f8b Klassiske damesolbriller - Let brun turtle | Brune glas her | EU's st\u00f8rste udvalg af LOCS solbriller | Vi sender fra EU - Ingen ekstra import udgifter","og_url":"https:\/\/locsshop.eu\/fr\/shop\/klassiske-damesolbriller-let-brun-turtle-brune-glas\/","og_site_name":"Locs Sunglasses - LOCS Supplier in EU","article_modified_time":"2024-08-12T12:41:08+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/locsshop.eu\/wp-content\/uploads\/2023\/05\/23-054-BNTE.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/locsshop.eu\/shop\/klassiske-damesolbriller-let-brun-turtle-brune-glas\/","url":"https:\/\/locsshop.eu\/shop\/klassiske-damesolbriller-let-brun-turtle-brune-glas\/","name":"Lunettes de soleil classiques pour femmes - Tortue marron clair | Lunettes marron | Achetez en ligne ici | LOCS","isPartOf":{"@id":"https:\/\/locsshop.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/locsshop.eu\/shop\/klassiske-damesolbriller-let-brun-turtle-brune-glas\/#primaryimage"},"image":{"@id":"https:\/\/locsshop.eu\/shop\/klassiske-damesolbriller-let-brun-turtle-brune-glas\/#primaryimage"},"thumbnailUrl":"https:\/\/locsshop.eu\/wp-content\/uploads\/2023\/05\/23-054-BNTE.jpg","datePublished":"2023-05-09T11:09:52+00:00","dateModified":"2024-08-12T12:41:08+00:00","description":"Acheter Lunettes de soleil classiques pour femmes - Tortue marron clair | Lunettes marron ici | La plus grande s\u00e9lection de lunettes de soleil LOCS de l&#039;UE | Nous exp\u00e9dions depuis l&#039;UE - Pas de frais d&#039;importation suppl\u00e9mentaires","breadcrumb":{"@id":"https:\/\/locsshop.eu\/shop\/klassiske-damesolbriller-let-brun-turtle-brune-glas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/locsshop.eu\/shop\/klassiske-damesolbriller-let-brun-turtle-brune-glas\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/locsshop.eu\/shop\/klassiske-damesolbriller-let-brun-turtle-brune-glas\/#primaryimage","url":"https:\/\/locsshop.eu\/wp-content\/uploads\/2023\/05\/23-054-BNTE.jpg","contentUrl":"https:\/\/locsshop.eu\/wp-content\/uploads\/2023\/05\/23-054-BNTE.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/locsshop.eu\/shop\/klassiske-damesolbriller-let-brun-turtle-brune-glas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/locsshop.eu\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/locsshop.eu\/shop\/"},{"@type":"ListItem","position":3,"name":"Klassiske damesolbriller &#8211; Let brun turtle | Brune glas"}]},{"@type":"WebSite","@id":"https:\/\/locsshop.eu\/#website","url":"https:\/\/locsshop.eu\/","name":"Lunettes de soleil Locs - Fournisseur LOCS dans l&#039;UE","description":"Nous vendons des lunettes de soleil LOCS bon march\u00e9","publisher":{"@id":"https:\/\/locsshop.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/locsshop.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/locsshop.eu\/#organization","name":"Locsshop.eu","url":"https:\/\/locsshop.eu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/locsshop.eu\/#\/schema\/logo\/image\/","url":"https:\/\/locsshop.eu\/wp-content\/uploads\/2022\/02\/Locsshop-logo.png","contentUrl":"https:\/\/locsshop.eu\/wp-content\/uploads\/2022\/02\/Locsshop-logo.png","width":930,"height":200,"caption":"Locsshop.eu"},"image":{"@id":"https:\/\/locsshop.eu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/locsshop.eu\/fr\/wp-json\/wp\/v2\/product\/10242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/locsshop.eu\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/locsshop.eu\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/locsshop.eu\/fr\/wp-json\/wp\/v2\/comments?post=10242"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/locsshop.eu\/fr\/wp-json\/wp\/v2\/media\/10243"}],"wp:attachment":[{"href":"https:\/\/locsshop.eu\/fr\/wp-json\/wp\/v2\/media?parent=10242"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/locsshop.eu\/fr\/wp-json\/wp\/v2\/product_brand?post=10242"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/locsshop.eu\/fr\/wp-json\/wp\/v2\/product_cat?post=10242"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/locsshop.eu\/fr\/wp-json\/wp\/v2\/product_tag?post=10242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}